{"id":5743,"count":1,"description":"","link":"https:\/\/catholic-television.com\/ur\/tag\/%d8%ae%d8%af%d8%a7%d9%88%d9%86%d8%af-%da%a9%d9%88-%d8%ac%d8%a7%d9%86%d9%86%d8%a7\/","name":"\u062e\u062f\u0627\u0648\u0646\u062f \u06a9\u0648 \u062c\u0627\u0646\u0646\u0627","slug":"%d8%ae%d8%af%d8%a7%d9%88%d9%86%d8%af-%da%a9%d9%88-%d8%ac%d8%a7%d9%86%d9%86%d8%a7","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u062e\u062f\u0627\u0648\u0646\u062f \u06a9\u0648 \u062c\u0627\u0646\u0646\u0627 Archives - Catholic-television<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/catholic-television.com\/ur\/tag\/%d8%ae%d8%af%d8%a7%d9%88%d9%86%d8%af-%da%a9%d9%88-%d8%ac%d8%a7%d9%86%d9%86%d8%a7\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u062e\u062f\u0627\u0648\u0646\u062f \u06a9\u0648 \u062c\u0627\u0646\u0646\u0627 Archives - Catholic-television\" \/>\n<meta property=\"og:url\" content=\"https:\/\/catholic-television.com\/ur\/tag\/%d8%ae%d8%af%d8%a7%d9%88%d9%86%d8%af-%da%a9%d9%88-%d8%ac%d8%a7%d9%86%d9%86%d8%a7\/\" \/>\n<meta property=\"og:site_name\" content=\"Catholic-television\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@catholictele\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/catholic-television.com\\\/ur\\\/tag\\\/%d8%ae%d8%af%d8%a7%d9%88%d9%86%d8%af-%da%a9%d9%88-%d8%ac%d8%a7%d9%86%d9%86%d8%a7\\\/\",\"url\":\"https:\\\/\\\/catholic-television.com\\\/ur\\\/tag\\\/%d8%ae%d8%af%d8%a7%d9%88%d9%86%d8%af-%da%a9%d9%88-%d8%ac%d8%a7%d9%86%d9%86%d8%a7\\\/\",\"name\":\"\u062e\u062f\u0627\u0648\u0646\u062f \u06a9\u0648 \u062c\u0627\u0646\u0646\u0627 Archives - Catholic-television\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/catholic-television.com\\\/ur\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/catholic-television.com\\\/ur\\\/tag\\\/%d8%ae%d8%af%d8%a7%d9%88%d9%86%d8%af-%da%a9%d9%88-%d8%ac%d8%a7%d9%86%d9%86%d8%a7\\\/#breadcrumb\"},\"inLanguage\":\"ur\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/catholic-television.com\\\/ur\\\/tag\\\/%d8%ae%d8%af%d8%a7%d9%88%d9%86%d8%af-%da%a9%d9%88-%d8%ac%d8%a7%d9%86%d9%86%d8%a7\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/catholic-television.com\\\/ur\\\/?lang=ur\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u062e\u062f\u0627\u0648\u0646\u062f \u06a9\u0648 \u062c\u0627\u0646\u0646\u0627\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/catholic-television.com\\\/ur\\\/#website\",\"url\":\"https:\\\/\\\/catholic-television.com\\\/ur\\\/\",\"name\":\"Catholic-television\",\"description\":\"Catholic Television\",\"publisher\":{\"@id\":\"https:\\\/\\\/catholic-television.com\\\/ur\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/catholic-television.com\\\/ur\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ur\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/catholic-television.com\\\/ur\\\/#organization\",\"name\":\"Catholic-television\",\"url\":\"https:\\\/\\\/catholic-television.com\\\/ur\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ur\",\"@id\":\"https:\\\/\\\/catholic-television.com\\\/ur\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/catholic-television.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/catholic-tv_ok2.png\",\"contentUrl\":\"https:\\\/\\\/catholic-television.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/catholic-tv_ok2.png\",\"width\":303,\"height\":99,\"caption\":\"Catholic-television\"},\"image\":{\"@id\":\"https:\\\/\\\/catholic-television.com\\\/ur\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/catholic.television.production\\\/\",\"https:\\\/\\\/x.com\\\/catholictele\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u062e\u062f\u0627\u0648\u0646\u062f \u06a9\u0648 \u062c\u0627\u0646\u0646\u0627 Archives - Catholic-television","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/catholic-television.com\/ur\/tag\/%d8%ae%d8%af%d8%a7%d9%88%d9%86%d8%af-%da%a9%d9%88-%d8%ac%d8%a7%d9%86%d9%86%d8%a7\/","og_locale":"en_US","og_type":"article","og_title":"\u062e\u062f\u0627\u0648\u0646\u062f \u06a9\u0648 \u062c\u0627\u0646\u0646\u0627 Archives - Catholic-television","og_url":"https:\/\/catholic-television.com\/ur\/tag\/%d8%ae%d8%af%d8%a7%d9%88%d9%86%d8%af-%da%a9%d9%88-%d8%ac%d8%a7%d9%86%d9%86%d8%a7\/","og_site_name":"Catholic-television","twitter_card":"summary_large_image","twitter_site":"@catholictele","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/catholic-television.com\/ur\/tag\/%d8%ae%d8%af%d8%a7%d9%88%d9%86%d8%af-%da%a9%d9%88-%d8%ac%d8%a7%d9%86%d9%86%d8%a7\/","url":"https:\/\/catholic-television.com\/ur\/tag\/%d8%ae%d8%af%d8%a7%d9%88%d9%86%d8%af-%da%a9%d9%88-%d8%ac%d8%a7%d9%86%d9%86%d8%a7\/","name":"\u062e\u062f\u0627\u0648\u0646\u062f \u06a9\u0648 \u062c\u0627\u0646\u0646\u0627 Archives - Catholic-television","isPartOf":{"@id":"https:\/\/catholic-television.com\/ur\/#website"},"breadcrumb":{"@id":"https:\/\/catholic-television.com\/ur\/tag\/%d8%ae%d8%af%d8%a7%d9%88%d9%86%d8%af-%da%a9%d9%88-%d8%ac%d8%a7%d9%86%d9%86%d8%a7\/#breadcrumb"},"inLanguage":"ur"},{"@type":"BreadcrumbList","@id":"https:\/\/catholic-television.com\/ur\/tag\/%d8%ae%d8%af%d8%a7%d9%88%d9%86%d8%af-%da%a9%d9%88-%d8%ac%d8%a7%d9%86%d9%86%d8%a7\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/catholic-television.com\/ur\/?lang=ur"},{"@type":"ListItem","position":2,"name":"\u062e\u062f\u0627\u0648\u0646\u062f \u06a9\u0648 \u062c\u0627\u0646\u0646\u0627"}]},{"@type":"WebSite","@id":"https:\/\/catholic-television.com\/ur\/#website","url":"https:\/\/catholic-television.com\/ur\/","name":"Catholic-television","description":"Catholic Television","publisher":{"@id":"https:\/\/catholic-television.com\/ur\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/catholic-television.com\/ur\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ur"},{"@type":"Organization","@id":"https:\/\/catholic-television.com\/ur\/#organization","name":"Catholic-television","url":"https:\/\/catholic-television.com\/ur\/","logo":{"@type":"ImageObject","inLanguage":"ur","@id":"https:\/\/catholic-television.com\/ur\/#\/schema\/logo\/image\/","url":"https:\/\/catholic-television.com\/wp-content\/uploads\/2019\/06\/catholic-tv_ok2.png","contentUrl":"https:\/\/catholic-television.com\/wp-content\/uploads\/2019\/06\/catholic-tv_ok2.png","width":303,"height":99,"caption":"Catholic-television"},"image":{"@id":"https:\/\/catholic-television.com\/ur\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/catholic.television.production\/","https:\/\/x.com\/catholictele"]}]}},"_links":{"self":[{"href":"https:\/\/catholic-television.com\/ur\/wp-json\/wp\/v2\/tags\/5743","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/catholic-television.com\/ur\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/catholic-television.com\/ur\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/catholic-television.com\/ur\/wp-json\/wp\/v2\/posts?tags=5743"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}