{"id":31194,"count":1,"description":"","link":"https:\/\/catholic-television.com\/hi\/tag\/%e0%a4%b8%e0%a4%82%e0%a4%b8%e0%a4%be%e0%a4%b0\/","name":"\u0938\u0902\u0938\u093e\u0930","slug":"%e0%a4%b8%e0%a4%82%e0%a4%b8%e0%a4%be%e0%a4%b0","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0938\u0902\u0938\u093e\u0930 Archives - Catholic-television<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/catholic-television.com\/hi\/tag\/%e0%a4%b8%e0%a4%82%e0%a4%b8%e0%a4%be%e0%a4%b0\/\" \/>\n<meta property=\"og:locale\" content=\"hi_IN\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0938\u0902\u0938\u093e\u0930 Archives - Catholic-television\" \/>\n<meta property=\"og:url\" content=\"https:\/\/catholic-television.com\/hi\/tag\/%e0%a4%b8%e0%a4%82%e0%a4%b8%e0%a4%be%e0%a4%b0\/\" \/>\n<meta property=\"og:site_name\" content=\"Catholic-television\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@catholictele\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/catholic-television.com\\\/hi\\\/tag\\\/%e0%a4%b8%e0%a4%82%e0%a4%b8%e0%a4%be%e0%a4%b0\\\/\",\"url\":\"https:\\\/\\\/catholic-television.com\\\/hi\\\/tag\\\/%e0%a4%b8%e0%a4%82%e0%a4%b8%e0%a4%be%e0%a4%b0\\\/\",\"name\":\"\u0938\u0902\u0938\u093e\u0930 Archives - Catholic-television\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/catholic-television.com\\\/hi\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/catholic-television.com\\\/hi\\\/tag\\\/%e0%a4%b8%e0%a4%82%e0%a4%b8%e0%a4%be%e0%a4%b0\\\/#breadcrumb\"},\"inLanguage\":\"hi-IN\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/catholic-television.com\\\/hi\\\/tag\\\/%e0%a4%b8%e0%a4%82%e0%a4%b8%e0%a4%be%e0%a4%b0\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u092e\u0941\u0916\u094d\u092f\u092a\u0943\u0937\u094d\u0920\",\"item\":\"https:\\\/\\\/catholic-television.com\\\/hi\\\/?lang=hi\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0938\u0902\u0938\u093e\u0930\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/catholic-television.com\\\/hi\\\/#website\",\"url\":\"https:\\\/\\\/catholic-television.com\\\/hi\\\/\",\"name\":\"Catholic-television\",\"description\":\"Catholic Television\",\"publisher\":{\"@id\":\"https:\\\/\\\/catholic-television.com\\\/hi\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/catholic-television.com\\\/hi\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"hi-IN\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/catholic-television.com\\\/hi\\\/#organization\",\"name\":\"Catholic-television\",\"url\":\"https:\\\/\\\/catholic-television.com\\\/hi\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"hi-IN\",\"@id\":\"https:\\\/\\\/catholic-television.com\\\/hi\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/catholic-television.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/catholic-tv_ok2.png\",\"contentUrl\":\"https:\\\/\\\/catholic-television.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/catholic-tv_ok2.png\",\"width\":303,\"height\":99,\"caption\":\"Catholic-television\"},\"image\":{\"@id\":\"https:\\\/\\\/catholic-television.com\\\/hi\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/catholic.television.production\\\/\",\"https:\\\/\\\/x.com\\\/catholictele\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0938\u0902\u0938\u093e\u0930 Archives - Catholic-television","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/catholic-television.com\/hi\/tag\/%e0%a4%b8%e0%a4%82%e0%a4%b8%e0%a4%be%e0%a4%b0\/","og_locale":"hi_IN","og_type":"article","og_title":"\u0938\u0902\u0938\u093e\u0930 Archives - Catholic-television","og_url":"https:\/\/catholic-television.com\/hi\/tag\/%e0%a4%b8%e0%a4%82%e0%a4%b8%e0%a4%be%e0%a4%b0\/","og_site_name":"Catholic-television","twitter_card":"summary_large_image","twitter_site":"@catholictele","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/catholic-television.com\/hi\/tag\/%e0%a4%b8%e0%a4%82%e0%a4%b8%e0%a4%be%e0%a4%b0\/","url":"https:\/\/catholic-television.com\/hi\/tag\/%e0%a4%b8%e0%a4%82%e0%a4%b8%e0%a4%be%e0%a4%b0\/","name":"\u0938\u0902\u0938\u093e\u0930 Archives - Catholic-television","isPartOf":{"@id":"https:\/\/catholic-television.com\/hi\/#website"},"breadcrumb":{"@id":"https:\/\/catholic-television.com\/hi\/tag\/%e0%a4%b8%e0%a4%82%e0%a4%b8%e0%a4%be%e0%a4%b0\/#breadcrumb"},"inLanguage":"hi-IN"},{"@type":"BreadcrumbList","@id":"https:\/\/catholic-television.com\/hi\/tag\/%e0%a4%b8%e0%a4%82%e0%a4%b8%e0%a4%be%e0%a4%b0\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u092e\u0941\u0916\u094d\u092f\u092a\u0943\u0937\u094d\u0920","item":"https:\/\/catholic-television.com\/hi\/?lang=hi"},{"@type":"ListItem","position":2,"name":"\u0938\u0902\u0938\u093e\u0930"}]},{"@type":"WebSite","@id":"https:\/\/catholic-television.com\/hi\/#website","url":"https:\/\/catholic-television.com\/hi\/","name":"Catholic-television","description":"Catholic Television","publisher":{"@id":"https:\/\/catholic-television.com\/hi\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/catholic-television.com\/hi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"hi-IN"},{"@type":"Organization","@id":"https:\/\/catholic-television.com\/hi\/#organization","name":"Catholic-television","url":"https:\/\/catholic-television.com\/hi\/","logo":{"@type":"ImageObject","inLanguage":"hi-IN","@id":"https:\/\/catholic-television.com\/hi\/#\/schema\/logo\/image\/","url":"https:\/\/catholic-television.com\/wp-content\/uploads\/2019\/06\/catholic-tv_ok2.png","contentUrl":"https:\/\/catholic-television.com\/wp-content\/uploads\/2019\/06\/catholic-tv_ok2.png","width":303,"height":99,"caption":"Catholic-television"},"image":{"@id":"https:\/\/catholic-television.com\/hi\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/catholic.television.production\/","https:\/\/x.com\/catholictele"]}]}},"_links":{"self":[{"href":"https:\/\/catholic-television.com\/hi\/wp-json\/wp\/v2\/tags\/31194","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/catholic-television.com\/hi\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/catholic-television.com\/hi\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/catholic-television.com\/hi\/wp-json\/wp\/v2\/posts?tags=31194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}