{"id":12555,"count":1,"description":"","link":"https:\/\/catholic-television.com\/es\/tag\/abandon\/","name":"Abandon","slug":"abandon","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Abandon Archives - Catholic-television<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/catholic-television.com\/es\/tag\/abandon\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Abandon Archives - Catholic-television\" \/>\n<meta property=\"og:url\" content=\"https:\/\/catholic-television.com\/es\/tag\/abandon\/\" \/>\n<meta property=\"og:site_name\" content=\"Catholic-television\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@catholictele\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/tag\\\/abandon\\\/\",\"url\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/tag\\\/abandon\\\/\",\"name\":\"Abandon Archives - Catholic-television\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/tag\\\/abandon\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/tag\\\/abandon\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/?lang=es\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Abandon\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/\",\"name\":\"Catholic-television\",\"description\":\"Catholic Television\",\"publisher\":{\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/#organization\",\"name\":\"Catholic-television\",\"url\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/catholic-television.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/catholic-tv_ok2.png\",\"contentUrl\":\"https:\\\/\\\/catholic-television.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/catholic-tv_ok2.png\",\"width\":303,\"height\":99,\"caption\":\"Catholic-television\"},\"image\":{\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/catholic.television.production\\\/\",\"https:\\\/\\\/x.com\\\/catholictele\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Abandon Archives - Catholic-television","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/catholic-television.com\/es\/tag\/abandon\/","og_locale":"es_ES","og_type":"article","og_title":"Abandon Archives - Catholic-television","og_url":"https:\/\/catholic-television.com\/es\/tag\/abandon\/","og_site_name":"Catholic-television","twitter_card":"summary_large_image","twitter_site":"@catholictele","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/catholic-television.com\/es\/tag\/abandon\/","url":"https:\/\/catholic-television.com\/es\/tag\/abandon\/","name":"Abandon Archives - Catholic-television","isPartOf":{"@id":"https:\/\/catholic-television.com\/es\/#website"},"breadcrumb":{"@id":"https:\/\/catholic-television.com\/es\/tag\/abandon\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/catholic-television.com\/es\/tag\/abandon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/catholic-television.com\/es\/?lang=es"},{"@type":"ListItem","position":2,"name":"Abandon"}]},{"@type":"WebSite","@id":"https:\/\/catholic-television.com\/es\/#website","url":"https:\/\/catholic-television.com\/es\/","name":"Catholic-television","description":"Catholic Television","publisher":{"@id":"https:\/\/catholic-television.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/catholic-television.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/catholic-television.com\/es\/#organization","name":"Catholic-television","url":"https:\/\/catholic-television.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/catholic-television.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/catholic-television.com\/wp-content\/uploads\/2019\/06\/catholic-tv_ok2.png","contentUrl":"https:\/\/catholic-television.com\/wp-content\/uploads\/2019\/06\/catholic-tv_ok2.png","width":303,"height":99,"caption":"Catholic-television"},"image":{"@id":"https:\/\/catholic-television.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/catholic.television.production\/","https:\/\/x.com\/catholictele"]}]}},"_links":{"self":[{"href":"https:\/\/catholic-television.com\/es\/wp-json\/wp\/v2\/tags\/12555","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/catholic-television.com\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/catholic-television.com\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/catholic-television.com\/es\/wp-json\/wp\/v2\/posts?tags=12555"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}