{"id":7951,"date":"2020-03-19T02:35:19","date_gmt":"2020-03-19T02:35:19","guid":{"rendered":"https:\/\/catholic-television.com\/wp-staging\/?p=7951\/"},"modified":"2020-03-19T02:35:19","modified_gmt":"2020-03-19T02:35:19","slug":"actitud-tiene-cristiano-ante-la-ira","status":"publish","type":"post","link":"https:\/\/catholic-television.com\/es\/actitud-tiene-cristiano-ante-la-ira\/","title":{"rendered":"\u00bfQu\u00e9 actitud tiene un cristiano ante la ira?"},"content":{"rendered":"<p style=\"text-align: justify\"><span style=\"color: #000000\"><strong>\u00bfQu\u00e9 actitud tiene un cristiano ante la ira?<\/strong><\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"color: #000000\"><strong>San Pablo dice: \u00abSi os indign\u00e1is, no llegu\u00e9is a pecar; que el sol no se ponga sobre vuestra ira\u00bb.<\/strong><\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"color: #000000\">La ira o c\u00f3lera es en primer lugar un afecto natural, como reacci\u00f3n a una injusticia experimentada. Pero cuando la c\u00f3lera se convierte en odio y se desea el mal del pr\u00f3jimo, lo que es un sentimiento natural se convierte en una falta grave contra la caridad. Toda ira incontrolada, especialmente el deseo de venganza, est\u00e1 dirigida contra la paz y altera \u00abla tranquilidad del orden\u00bb.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfQu\u00e9 actitud tiene un cristiano ante la ira? San Pablo dice: \u00abSi os indign\u00e1is, no llegu\u00e9is a pecar; que el sol no se ponga sobre vuestra ira\u00bb. La ira o c\u00f3lera es en primer lugar un afecto natural, como reacci\u00f3n a una injusticia experimentada. Pero cuando la c\u00f3lera se convierte en odio y se desea&hellip; <a class=\"more-link\" href=\"https:\/\/catholic-television.com\/es\/actitud-tiene-cristiano-ante-la-ira\/\">Seguir leyendo <span class=\"screen-reader-text\">\u00bfQu\u00e9 actitud tiene un cristiano ante la ira?<\/span><\/a><\/p>\n","protected":false},"author":7,"featured_media":7952,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[668,650],"tags":[22845,19588,22847,22848,22846,22843,22844,18172,22849,2074],"class_list":["post-7951","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bienvenidos","category-catequesis","tag-afecto-natural","tag-caridad","tag-desear-mal-projimo","tag-falta-grave","tag-injusticia-experimentada","tag-la-colera","tag-la-ira","tag-san-pablo","tag-tranquilidad-orden","tag-venganza","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfQu\u00e9 actitud tiene un cristiano ante la ira? | San Pablo | La c\u00f3lera | La ira<\/title>\n<meta name=\"description\" content=\"La ira o c\u00f3lera es en primer lugar un afecto natural, como reacci\u00f3n a una injusticia experimentada. Pero cuando la c\u00f3lera se convierte en odio y se...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/catholic-television.com\/es\/actitud-tiene-cristiano-ante-la-ira\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQu\u00e9 actitud tiene un cristiano ante la ira? | San Pablo | La c\u00f3lera | La ira\" \/>\n<meta property=\"og:description\" content=\"La ira o c\u00f3lera es en primer lugar un afecto natural, como reacci\u00f3n a una injusticia experimentada. Pero cuando la c\u00f3lera se convierte en odio y se...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/catholic-television.com\/es\/actitud-tiene-cristiano-ante-la-ira\/\" \/>\n<meta property=\"og:site_name\" content=\"Catholic-television\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/catholic.television.production\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-03-19T02:35:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/catholic-television.com\/wp-content\/uploads\/2020\/03\/\u00bfQu\u00e9-actitud-tiene-un-cristiano-ante-la-ira-San-Pablo-La-c\u00f3lera-La-ira.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"vlad\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@catholictele\" \/>\n<meta name=\"twitter:site\" content=\"@catholictele\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"vlad\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/actitud-tiene-cristiano-ante-la-ira\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/actitud-tiene-cristiano-ante-la-ira\\\/\"},\"author\":{\"name\":\"vlad\",\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/#\\\/schema\\\/person\\\/3188c12fc213ed75be05c8a3a8650318\"},\"headline\":\"\u00bfQu\u00e9 actitud tiene un cristiano ante la ira?\",\"datePublished\":\"2020-03-19T02:35:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/actitud-tiene-cristiano-ante-la-ira\\\/\"},\"wordCount\":107,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/actitud-tiene-cristiano-ante-la-ira\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/catholic-television.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/\u00bfQu\u00e9-actitud-tiene-un-cristiano-ante-la-ira-San-Pablo-La-c\u00f3lera-La-ira.jpg\",\"keywords\":[\"Afecto natural\",\"Caridad\",\"Desear mal pr\u00f3jimo\",\"Falta grave\",\"Injusticia experimentada\",\"La c\u00f3lera\",\"La ira\",\"San Pablo\",\"Tranquilidad orden\",\"venganza\"],\"articleSection\":[\"Bienvenidos\",\"Catequesis\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/catholic-television.com\\\/es\\\/actitud-tiene-cristiano-ante-la-ira\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/actitud-tiene-cristiano-ante-la-ira\\\/\",\"url\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/actitud-tiene-cristiano-ante-la-ira\\\/\",\"name\":\"\u00bfQu\u00e9 actitud tiene un cristiano ante la ira? | San Pablo | La c\u00f3lera | La ira\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/actitud-tiene-cristiano-ante-la-ira\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/actitud-tiene-cristiano-ante-la-ira\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/catholic-television.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/\u00bfQu\u00e9-actitud-tiene-un-cristiano-ante-la-ira-San-Pablo-La-c\u00f3lera-La-ira.jpg\",\"datePublished\":\"2020-03-19T02:35:19+00:00\",\"description\":\"La ira o c\u00f3lera es en primer lugar un afecto natural, como reacci\u00f3n a una injusticia experimentada. Pero cuando la c\u00f3lera se convierte en odio y se...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/actitud-tiene-cristiano-ante-la-ira\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/catholic-television.com\\\/es\\\/actitud-tiene-cristiano-ante-la-ira\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/actitud-tiene-cristiano-ante-la-ira\\\/#primaryimage\",\"url\":\"https:\\\/\\\/catholic-television.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/\u00bfQu\u00e9-actitud-tiene-un-cristiano-ante-la-ira-San-Pablo-La-c\u00f3lera-La-ira.jpg\",\"contentUrl\":\"https:\\\/\\\/catholic-television.com\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/\u00bfQu\u00e9-actitud-tiene-un-cristiano-ante-la-ira-San-Pablo-La-c\u00f3lera-La-ira.jpg\",\"width\":1024,\"height\":576,\"caption\":\"\u00bfQu\u00e9 actitud tiene un cristiano ante la ira? | San Pablo | La c\u00f3lera | La ira\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/actitud-tiene-cristiano-ante-la-ira\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/?lang=es\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfQu\u00e9 actitud tiene un cristiano ante la ira?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/\",\"name\":\"Catholic-television\",\"description\":\"Catholic Television\",\"publisher\":{\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/#organization\",\"name\":\"Catholic-television\",\"url\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/catholic-television.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/catholic-tv_ok2.png\",\"contentUrl\":\"https:\\\/\\\/catholic-television.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/catholic-tv_ok2.png\",\"width\":303,\"height\":99,\"caption\":\"Catholic-television\"},\"image\":{\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/catholic.television.production\\\/\",\"https:\\\/\\\/x.com\\\/catholictele\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/#\\\/schema\\\/person\\\/3188c12fc213ed75be05c8a3a8650318\",\"name\":\"vlad\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fc95831d9c48ad0da181a29b0820e0beb60a927341a41b7ffd6b73a4ef239589?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fc95831d9c48ad0da181a29b0820e0beb60a927341a41b7ffd6b73a4ef239589?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fc95831d9c48ad0da181a29b0820e0beb60a927341a41b7ffd6b73a4ef239589?s=96&d=mm&r=g\",\"caption\":\"vlad\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQu\u00e9 actitud tiene un cristiano ante la ira? | San Pablo | La c\u00f3lera | La ira","description":"La ira o c\u00f3lera es en primer lugar un afecto natural, como reacci\u00f3n a una injusticia experimentada. Pero cuando la c\u00f3lera se convierte en odio y se...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/catholic-television.com\/es\/actitud-tiene-cristiano-ante-la-ira\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfQu\u00e9 actitud tiene un cristiano ante la ira? | San Pablo | La c\u00f3lera | La ira","og_description":"La ira o c\u00f3lera es en primer lugar un afecto natural, como reacci\u00f3n a una injusticia experimentada. Pero cuando la c\u00f3lera se convierte en odio y se...","og_url":"https:\/\/catholic-television.com\/es\/actitud-tiene-cristiano-ante-la-ira\/","og_site_name":"Catholic-television","article_publisher":"https:\/\/www.facebook.com\/catholic.television.production\/","article_published_time":"2020-03-19T02:35:19+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/catholic-television.com\/wp-content\/uploads\/2020\/03\/\u00bfQu\u00e9-actitud-tiene-un-cristiano-ante-la-ira-San-Pablo-La-c\u00f3lera-La-ira.jpg","type":"image\/jpeg"}],"author":"vlad","twitter_card":"summary_large_image","twitter_creator":"@catholictele","twitter_site":"@catholictele","twitter_misc":{"Escrito por":"vlad"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/catholic-television.com\/es\/actitud-tiene-cristiano-ante-la-ira\/#article","isPartOf":{"@id":"https:\/\/catholic-television.com\/es\/actitud-tiene-cristiano-ante-la-ira\/"},"author":{"name":"vlad","@id":"https:\/\/catholic-television.com\/es\/#\/schema\/person\/3188c12fc213ed75be05c8a3a8650318"},"headline":"\u00bfQu\u00e9 actitud tiene un cristiano ante la ira?","datePublished":"2020-03-19T02:35:19+00:00","mainEntityOfPage":{"@id":"https:\/\/catholic-television.com\/es\/actitud-tiene-cristiano-ante-la-ira\/"},"wordCount":107,"commentCount":0,"publisher":{"@id":"https:\/\/catholic-television.com\/es\/#organization"},"image":{"@id":"https:\/\/catholic-television.com\/es\/actitud-tiene-cristiano-ante-la-ira\/#primaryimage"},"thumbnailUrl":"https:\/\/catholic-television.com\/wp-content\/uploads\/2020\/03\/\u00bfQu\u00e9-actitud-tiene-un-cristiano-ante-la-ira-San-Pablo-La-c\u00f3lera-La-ira.jpg","keywords":["Afecto natural","Caridad","Desear mal pr\u00f3jimo","Falta grave","Injusticia experimentada","La c\u00f3lera","La ira","San Pablo","Tranquilidad orden","venganza"],"articleSection":["Bienvenidos","Catequesis"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/catholic-television.com\/es\/actitud-tiene-cristiano-ante-la-ira\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/catholic-television.com\/es\/actitud-tiene-cristiano-ante-la-ira\/","url":"https:\/\/catholic-television.com\/es\/actitud-tiene-cristiano-ante-la-ira\/","name":"\u00bfQu\u00e9 actitud tiene un cristiano ante la ira? | San Pablo | La c\u00f3lera | La ira","isPartOf":{"@id":"https:\/\/catholic-television.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/catholic-television.com\/es\/actitud-tiene-cristiano-ante-la-ira\/#primaryimage"},"image":{"@id":"https:\/\/catholic-television.com\/es\/actitud-tiene-cristiano-ante-la-ira\/#primaryimage"},"thumbnailUrl":"https:\/\/catholic-television.com\/wp-content\/uploads\/2020\/03\/\u00bfQu\u00e9-actitud-tiene-un-cristiano-ante-la-ira-San-Pablo-La-c\u00f3lera-La-ira.jpg","datePublished":"2020-03-19T02:35:19+00:00","description":"La ira o c\u00f3lera es en primer lugar un afecto natural, como reacci\u00f3n a una injusticia experimentada. Pero cuando la c\u00f3lera se convierte en odio y se...","breadcrumb":{"@id":"https:\/\/catholic-television.com\/es\/actitud-tiene-cristiano-ante-la-ira\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/catholic-television.com\/es\/actitud-tiene-cristiano-ante-la-ira\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/catholic-television.com\/es\/actitud-tiene-cristiano-ante-la-ira\/#primaryimage","url":"https:\/\/catholic-television.com\/wp-content\/uploads\/2020\/03\/\u00bfQu\u00e9-actitud-tiene-un-cristiano-ante-la-ira-San-Pablo-La-c\u00f3lera-La-ira.jpg","contentUrl":"https:\/\/catholic-television.com\/wp-content\/uploads\/2020\/03\/\u00bfQu\u00e9-actitud-tiene-un-cristiano-ante-la-ira-San-Pablo-La-c\u00f3lera-La-ira.jpg","width":1024,"height":576,"caption":"\u00bfQu\u00e9 actitud tiene un cristiano ante la ira? | San Pablo | La c\u00f3lera | La ira"},{"@type":"BreadcrumbList","@id":"https:\/\/catholic-television.com\/es\/actitud-tiene-cristiano-ante-la-ira\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/catholic-television.com\/es\/?lang=es"},{"@type":"ListItem","position":2,"name":"\u00bfQu\u00e9 actitud tiene un cristiano ante la ira?"}]},{"@type":"WebSite","@id":"https:\/\/catholic-television.com\/es\/#website","url":"https:\/\/catholic-television.com\/es\/","name":"Catholic-television","description":"Catholic Television","publisher":{"@id":"https:\/\/catholic-television.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/catholic-television.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/catholic-television.com\/es\/#organization","name":"Catholic-television","url":"https:\/\/catholic-television.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/catholic-television.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/catholic-television.com\/wp-content\/uploads\/2019\/06\/catholic-tv_ok2.png","contentUrl":"https:\/\/catholic-television.com\/wp-content\/uploads\/2019\/06\/catholic-tv_ok2.png","width":303,"height":99,"caption":"Catholic-television"},"image":{"@id":"https:\/\/catholic-television.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/catholic.television.production\/","https:\/\/x.com\/catholictele"]},{"@type":"Person","@id":"https:\/\/catholic-television.com\/es\/#\/schema\/person\/3188c12fc213ed75be05c8a3a8650318","name":"vlad","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/fc95831d9c48ad0da181a29b0820e0beb60a927341a41b7ffd6b73a4ef239589?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fc95831d9c48ad0da181a29b0820e0beb60a927341a41b7ffd6b73a4ef239589?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fc95831d9c48ad0da181a29b0820e0beb60a927341a41b7ffd6b73a4ef239589?s=96&d=mm&r=g","caption":"vlad"}}]}},"_links":{"self":[{"href":"https:\/\/catholic-television.com\/es\/wp-json\/wp\/v2\/posts\/7951","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/catholic-television.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/catholic-television.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/catholic-television.com\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/catholic-television.com\/es\/wp-json\/wp\/v2\/comments?post=7951"}],"version-history":[{"count":1,"href":"https:\/\/catholic-television.com\/es\/wp-json\/wp\/v2\/posts\/7951\/revisions"}],"predecessor-version":[{"id":7953,"href":"https:\/\/catholic-television.com\/es\/wp-json\/wp\/v2\/posts\/7951\/revisions\/7953"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/catholic-television.com\/es\/wp-json\/wp\/v2\/media\/7952"}],"wp:attachment":[{"href":"https:\/\/catholic-television.com\/es\/wp-json\/wp\/v2\/media?parent=7951"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/catholic-television.com\/es\/wp-json\/wp\/v2\/categories?post=7951"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/catholic-television.com\/es\/wp-json\/wp\/v2\/tags?post=7951"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}