{"id":6719,"date":"2020-02-04T02:49:29","date_gmt":"2020-02-04T02:49:29","guid":{"rendered":"https:\/\/catholic-television.com\/wp-staging\/?p=6719\/"},"modified":"2020-02-06T07:24:45","modified_gmt":"2020-02-06T07:24:45","slug":"que-es-el-cielo","status":"publish","type":"post","link":"https:\/\/catholic-television.com\/es\/que-es-el-cielo\/","title":{"rendered":"\u00bfQu\u00e9 es el cielo?"},"content":{"rendered":"<p style=\"text-align: justify\"><strong><span style=\"color: #000000\">\u00bfQu\u00e9 es el cielo?<\/span><\/strong><\/p>\n<p style=\"text-align: justify\"><span style=\"color: #000000\"><strong>El cielo es el \u00abmedio\u00bb de Dios, la morada de los \u00e1ngeles y los santos y la meta de la Creaci\u00f3n. Con la expresi\u00f3n \u00abcielo y tierra\u00bb designamos la totalidad de la realidad creada.<\/strong><\/span><\/p>\n<p style=\"text-align: justify\"><span style=\"color: #000000\">El cielo no es un lugar en el universo. Es un estado en el m\u00e1s all\u00e1. El cielo est\u00e1 all\u00ed donde se cumple la voluntad de Dios sin ninguna resistencia. El cielo existe cuando se da la vida en su m\u00e1xima intensidad y santidad (vida que no se puede encontrar como tal en la tierra). Cuando con la ayuda de Dios vayamos alg\u00fan d\u00eda al cielo, entonces nos espera lo \u00abque ni el ojo vio, ni el o\u00eddo oy\u00f3, ni el hombre puede pensar lo que Dios ha preparado para los que lo aman\u00bb.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfQu\u00e9 es el cielo? El cielo es el \u00abmedio\u00bb de Dios, la morada de los \u00e1ngeles y los santos y la meta de la Creaci\u00f3n. Con la expresi\u00f3n \u00abcielo y tierra\u00bb designamos la totalidad de la realidad creada. El cielo no es un lugar en el universo. Es un estado en el m\u00e1s all\u00e1. El&hellip; <a class=\"more-link\" href=\"https:\/\/catholic-television.com\/es\/que-es-el-cielo\/\">Seguir leyendo <span class=\"screen-reader-text\">\u00bfQu\u00e9 es el cielo?<\/span><\/a><\/p>\n","protected":false},"author":7,"featured_media":6720,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[668,650],"tags":[9753,18580,18184,18584,18581,18585,18582,18583,997],"class_list":["post-6719","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bienvenidos","category-catequesis","tag-angeles","tag-cielo","tag-creacion","tag-mas-alla","tag-morada","tag-santidad","tag-santos","tag-universo","tag-voluntad-de-dios","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00bfQu\u00e9 es el cielo? | Cielo | Morada \u00e1ngeles | Santos | Creaci\u00f3n | Universo<\/title>\n<meta name=\"description\" content=\"Es el cielo. El cielo no es un lugar en el universo. Es un estado en el m\u00e1s all\u00e1. El cielo est\u00e1 all\u00ed donde se cumple la voluntad de Dios sin ninguna...\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/catholic-television.com\/es\/que-es-el-cielo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfQu\u00e9 es el cielo? | Cielo | Morada \u00e1ngeles | Santos | Creaci\u00f3n | Universo\" \/>\n<meta property=\"og:description\" content=\"Es el cielo. El cielo no es un lugar en el universo. Es un estado en el m\u00e1s all\u00e1. El cielo est\u00e1 all\u00ed donde se cumple la voluntad de Dios sin ninguna...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/catholic-television.com\/es\/que-es-el-cielo\/\" \/>\n<meta property=\"og:site_name\" content=\"Catholic-television\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/catholic.television.production\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-02-04T02:49:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-02-06T07:24:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/catholic-television.com\/wp-content\/uploads\/2020\/02\/\u00bfQu\u00e9-es-el-cielo-Cielo-Morada-\u00c1ngeles-Santos-Creaci\u00f3n-Universo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"vlad\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@catholictele\" \/>\n<meta name=\"twitter:site\" content=\"@catholictele\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"vlad\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/que-es-el-cielo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/que-es-el-cielo\\\/\"},\"author\":{\"name\":\"vlad\",\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/#\\\/schema\\\/person\\\/3188c12fc213ed75be05c8a3a8650318\"},\"headline\":\"\u00bfQu\u00e9 es el cielo?\",\"datePublished\":\"2020-02-04T02:49:29+00:00\",\"dateModified\":\"2020-02-06T07:24:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/que-es-el-cielo\\\/\"},\"wordCount\":143,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/que-es-el-cielo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/catholic-television.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/\u00bfQu\u00e9-es-el-cielo-Cielo-Morada-\u00c1ngeles-Santos-Creaci\u00f3n-Universo.jpg\",\"keywords\":[\"\u00e1ngeles\",\"Cielo\",\"Creaci\u00f3n\",\"M\u00e1s all\u00e1\",\"Morada\",\"Santidad\",\"Santos\",\"Universo\",\"voluntad de Dios\"],\"articleSection\":[\"Bienvenidos\",\"Catequesis\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/catholic-television.com\\\/es\\\/que-es-el-cielo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/que-es-el-cielo\\\/\",\"url\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/que-es-el-cielo\\\/\",\"name\":\"\u00bfQu\u00e9 es el cielo? | Cielo | Morada \u00e1ngeles | Santos | Creaci\u00f3n | Universo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/que-es-el-cielo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/que-es-el-cielo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/catholic-television.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/\u00bfQu\u00e9-es-el-cielo-Cielo-Morada-\u00c1ngeles-Santos-Creaci\u00f3n-Universo.jpg\",\"datePublished\":\"2020-02-04T02:49:29+00:00\",\"dateModified\":\"2020-02-06T07:24:45+00:00\",\"description\":\"Es el cielo. El cielo no es un lugar en el universo. Es un estado en el m\u00e1s all\u00e1. El cielo est\u00e1 all\u00ed donde se cumple la voluntad de Dios sin ninguna...\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/que-es-el-cielo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/catholic-television.com\\\/es\\\/que-es-el-cielo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/que-es-el-cielo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/catholic-television.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/\u00bfQu\u00e9-es-el-cielo-Cielo-Morada-\u00c1ngeles-Santos-Creaci\u00f3n-Universo.jpg\",\"contentUrl\":\"https:\\\/\\\/catholic-television.com\\\/wp-content\\\/uploads\\\/2020\\\/02\\\/\u00bfQu\u00e9-es-el-cielo-Cielo-Morada-\u00c1ngeles-Santos-Creaci\u00f3n-Universo.jpg\",\"width\":1024,\"height\":576,\"caption\":\"\u00bfQu\u00e9 es el cielo? | Cielo | Morada \u00e1ngeles | Santos | Creaci\u00f3n | Universo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/que-es-el-cielo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/?lang=es\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfQu\u00e9 es el cielo?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/\",\"name\":\"Catholic-television\",\"description\":\"Catholic Television\",\"publisher\":{\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/#organization\",\"name\":\"Catholic-television\",\"url\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/catholic-television.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/catholic-tv_ok2.png\",\"contentUrl\":\"https:\\\/\\\/catholic-television.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/catholic-tv_ok2.png\",\"width\":303,\"height\":99,\"caption\":\"Catholic-television\"},\"image\":{\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/catholic.television.production\\\/\",\"https:\\\/\\\/x.com\\\/catholictele\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/#\\\/schema\\\/person\\\/3188c12fc213ed75be05c8a3a8650318\",\"name\":\"vlad\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fc95831d9c48ad0da181a29b0820e0beb60a927341a41b7ffd6b73a4ef239589?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fc95831d9c48ad0da181a29b0820e0beb60a927341a41b7ffd6b73a4ef239589?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/fc95831d9c48ad0da181a29b0820e0beb60a927341a41b7ffd6b73a4ef239589?s=96&d=mm&r=g\",\"caption\":\"vlad\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfQu\u00e9 es el cielo? | Cielo | Morada \u00e1ngeles | Santos | Creaci\u00f3n | Universo","description":"Es el cielo. El cielo no es un lugar en el universo. Es un estado en el m\u00e1s all\u00e1. El cielo est\u00e1 all\u00ed donde se cumple la voluntad de Dios sin ninguna...","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/catholic-television.com\/es\/que-es-el-cielo\/","og_locale":"es_ES","og_type":"article","og_title":"\u00bfQu\u00e9 es el cielo? | Cielo | Morada \u00e1ngeles | Santos | Creaci\u00f3n | Universo","og_description":"Es el cielo. El cielo no es un lugar en el universo. Es un estado en el m\u00e1s all\u00e1. El cielo est\u00e1 all\u00ed donde se cumple la voluntad de Dios sin ninguna...","og_url":"https:\/\/catholic-television.com\/es\/que-es-el-cielo\/","og_site_name":"Catholic-television","article_publisher":"https:\/\/www.facebook.com\/catholic.television.production\/","article_published_time":"2020-02-04T02:49:29+00:00","article_modified_time":"2020-02-06T07:24:45+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/catholic-television.com\/wp-content\/uploads\/2020\/02\/\u00bfQu\u00e9-es-el-cielo-Cielo-Morada-\u00c1ngeles-Santos-Creaci\u00f3n-Universo.jpg","type":"image\/jpeg"}],"author":"vlad","twitter_card":"summary_large_image","twitter_creator":"@catholictele","twitter_site":"@catholictele","twitter_misc":{"Escrito por":"vlad","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/catholic-television.com\/es\/que-es-el-cielo\/#article","isPartOf":{"@id":"https:\/\/catholic-television.com\/es\/que-es-el-cielo\/"},"author":{"name":"vlad","@id":"https:\/\/catholic-television.com\/es\/#\/schema\/person\/3188c12fc213ed75be05c8a3a8650318"},"headline":"\u00bfQu\u00e9 es el cielo?","datePublished":"2020-02-04T02:49:29+00:00","dateModified":"2020-02-06T07:24:45+00:00","mainEntityOfPage":{"@id":"https:\/\/catholic-television.com\/es\/que-es-el-cielo\/"},"wordCount":143,"commentCount":0,"publisher":{"@id":"https:\/\/catholic-television.com\/es\/#organization"},"image":{"@id":"https:\/\/catholic-television.com\/es\/que-es-el-cielo\/#primaryimage"},"thumbnailUrl":"https:\/\/catholic-television.com\/wp-content\/uploads\/2020\/02\/\u00bfQu\u00e9-es-el-cielo-Cielo-Morada-\u00c1ngeles-Santos-Creaci\u00f3n-Universo.jpg","keywords":["\u00e1ngeles","Cielo","Creaci\u00f3n","M\u00e1s all\u00e1","Morada","Santidad","Santos","Universo","voluntad de Dios"],"articleSection":["Bienvenidos","Catequesis"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/catholic-television.com\/es\/que-es-el-cielo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/catholic-television.com\/es\/que-es-el-cielo\/","url":"https:\/\/catholic-television.com\/es\/que-es-el-cielo\/","name":"\u00bfQu\u00e9 es el cielo? | Cielo | Morada \u00e1ngeles | Santos | Creaci\u00f3n | Universo","isPartOf":{"@id":"https:\/\/catholic-television.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/catholic-television.com\/es\/que-es-el-cielo\/#primaryimage"},"image":{"@id":"https:\/\/catholic-television.com\/es\/que-es-el-cielo\/#primaryimage"},"thumbnailUrl":"https:\/\/catholic-television.com\/wp-content\/uploads\/2020\/02\/\u00bfQu\u00e9-es-el-cielo-Cielo-Morada-\u00c1ngeles-Santos-Creaci\u00f3n-Universo.jpg","datePublished":"2020-02-04T02:49:29+00:00","dateModified":"2020-02-06T07:24:45+00:00","description":"Es el cielo. El cielo no es un lugar en el universo. Es un estado en el m\u00e1s all\u00e1. El cielo est\u00e1 all\u00ed donde se cumple la voluntad de Dios sin ninguna...","breadcrumb":{"@id":"https:\/\/catholic-television.com\/es\/que-es-el-cielo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/catholic-television.com\/es\/que-es-el-cielo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/catholic-television.com\/es\/que-es-el-cielo\/#primaryimage","url":"https:\/\/catholic-television.com\/wp-content\/uploads\/2020\/02\/\u00bfQu\u00e9-es-el-cielo-Cielo-Morada-\u00c1ngeles-Santos-Creaci\u00f3n-Universo.jpg","contentUrl":"https:\/\/catholic-television.com\/wp-content\/uploads\/2020\/02\/\u00bfQu\u00e9-es-el-cielo-Cielo-Morada-\u00c1ngeles-Santos-Creaci\u00f3n-Universo.jpg","width":1024,"height":576,"caption":"\u00bfQu\u00e9 es el cielo? | Cielo | Morada \u00e1ngeles | Santos | Creaci\u00f3n | Universo"},{"@type":"BreadcrumbList","@id":"https:\/\/catholic-television.com\/es\/que-es-el-cielo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/catholic-television.com\/es\/?lang=es"},{"@type":"ListItem","position":2,"name":"\u00bfQu\u00e9 es el cielo?"}]},{"@type":"WebSite","@id":"https:\/\/catholic-television.com\/es\/#website","url":"https:\/\/catholic-television.com\/es\/","name":"Catholic-television","description":"Catholic Television","publisher":{"@id":"https:\/\/catholic-television.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/catholic-television.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/catholic-television.com\/es\/#organization","name":"Catholic-television","url":"https:\/\/catholic-television.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/catholic-television.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/catholic-television.com\/wp-content\/uploads\/2019\/06\/catholic-tv_ok2.png","contentUrl":"https:\/\/catholic-television.com\/wp-content\/uploads\/2019\/06\/catholic-tv_ok2.png","width":303,"height":99,"caption":"Catholic-television"},"image":{"@id":"https:\/\/catholic-television.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/catholic.television.production\/","https:\/\/x.com\/catholictele"]},{"@type":"Person","@id":"https:\/\/catholic-television.com\/es\/#\/schema\/person\/3188c12fc213ed75be05c8a3a8650318","name":"vlad","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/fc95831d9c48ad0da181a29b0820e0beb60a927341a41b7ffd6b73a4ef239589?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/fc95831d9c48ad0da181a29b0820e0beb60a927341a41b7ffd6b73a4ef239589?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/fc95831d9c48ad0da181a29b0820e0beb60a927341a41b7ffd6b73a4ef239589?s=96&d=mm&r=g","caption":"vlad"}}]}},"_links":{"self":[{"href":"https:\/\/catholic-television.com\/es\/wp-json\/wp\/v2\/posts\/6719","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/catholic-television.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/catholic-television.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/catholic-television.com\/es\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/catholic-television.com\/es\/wp-json\/wp\/v2\/comments?post=6719"}],"version-history":[{"count":1,"href":"https:\/\/catholic-television.com\/es\/wp-json\/wp\/v2\/posts\/6719\/revisions"}],"predecessor-version":[{"id":6721,"href":"https:\/\/catholic-television.com\/es\/wp-json\/wp\/v2\/posts\/6719\/revisions\/6721"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/catholic-television.com\/es\/wp-json\/wp\/v2\/media\/6720"}],"wp:attachment":[{"href":"https:\/\/catholic-television.com\/es\/wp-json\/wp\/v2\/media?parent=6719"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/catholic-television.com\/es\/wp-json\/wp\/v2\/categories?post=6719"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/catholic-television.com\/es\/wp-json\/wp\/v2\/tags?post=6719"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}