{"id":4071,"date":"2019-09-26T20:20:51","date_gmt":"2019-09-26T20:20:51","guid":{"rendered":"https:\/\/catholic-television.com\/wp-staging\/?p=4071\/"},"modified":"2022-12-04T10:16:51","modified_gmt":"2022-12-04T10:16:51","slug":"santuario-de-la-virgen-de-covadonga","status":"publish","type":"post","link":"https:\/\/catholic-television.com\/es\/santuario-de-la-virgen-de-covadonga\/","title":{"rendered":"Santuario de la Virgen de Covadonga"},"content":{"rendered":"\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe title=\"Carta de San Francisco Javier a los jesuitas de Europa desde Amboina en la India\" width=\"750\" height=\"422\" src=\"https:\/\/www.youtube.com\/embed\/YCurcZeRkBo?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">La&nbsp;Santa Cueva de Covadonga&nbsp;es un santuario cat\u00f3lico&nbsp;situado en el Principado de Asturias en el norte de Espa\u00f1a. Se trata de una gruta en las estribaciones del Monte Auseva, en los Picos de Europa. Aqu\u00ed se encuentra la Virgen de Covadonga, tambi\u00e9n llamada cari\u00f1osamente por los asturianos \u00abLa Santina\u00bb.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">El nombre de Covadonga significa Cueva de la Se\u00f1ora, ya que procede de la expresi\u00f3n latina Cova Dominica, la cual se ha ido transformando hasta llegar a la palabra actual: Covadonga.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Poco antes de entrar en el t\u00fanel de la Santa Cueva, arriba a nuestra derecha podemos encontrar esta campana. Cumple una funci\u00f3n meramente decorativa, pesa 5000 Kg. Mide 3 metros de altura y es donaci\u00f3n al Santuario de un conde suizo (Sizzo-Noris) y de D. Luis Gonz\u00e1lez Herrero. La campana, obra de Xaviero Sortini y primer premio en la exposici\u00f3n universal de Par\u00eds de 1900, est\u00e1 bellamente decorada con im\u00e1genes de la Divina Comedia de Dante.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Al entrar en la cueva vemos a la gente en silencio, con gran respeto y devoci\u00f3n, encendiendo velas en actitud orante, pidiendo as\u00ed la intercesi\u00f3n de la Virgen para que Cristo, que es la Luz, ilumine nuestras vidas y disipe las tinieblas.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">La Santina es una imagen de Mar\u00eda muy querida por todo el pueblo asturiano, ya sea por motivos hist\u00f3ricos, tradici\u00f3n o por experiencia religiosa personal. Est\u00e1 arraigada profundamente en la gente de esta tierra y constituye uno de los signos con m\u00e1s fuerza y poder de convocatoria de todo Asturias.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">La talla que hoy tambi\u00e9n podemos ver de madera de roble es del siglo XVI. Sus medidas son 71,4 cm de altura, incluyendo la peana. La anchura llega a 46 cm, y la profundidad a 21. El Ni\u00f1o actual ha sido colocado en el a\u00f1o 1704, sobre la mano izquierda de la Madre.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">En su vestidura merece destacarse el manto que luce Nuestra Se\u00f1ora desde los hombros hasta los pies y cae en su parte posterior en \u00e1ngulo hasta la base de la peana. Sus colores cambian seg\u00fan los tiempos lit\u00fargicos. El manto m\u00e1s habitual es de color rojo p\u00farpura, con una cenefa dorada. Se completa con el jub\u00f3n, camisa de manga larga ce\u00f1ida al talle, y la basqui\u00f1a o falda con sencillas estampaciones de motivos florales.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Justo debajo de la Santa Cueva se encuentra la fuente de los 7 ca\u00f1os, tiene forma de copa de la que caen siete peque\u00f1os chorros, se le puede denominar fuente de los Sacramentos.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Aunque popularmente se le conoce como \u00abfuente del matrimonio\u00bb, porque una copla antigua del folklore asturiano dice: \u00abLa Virgen de Covadonga tiene una fuente muy clara, la ni\u00f1a que de ella beba dentro del a\u00f1o se casa\u00bb.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">D. Pelayo, primer rey del naciente reino asturiano y vencedor de la batalla de Covadonga sobre los bereberes con base en Gij\u00f3n, estableci\u00f3 la primera capital de Asturias en Cangas de On\u00eds, a principios del siglo VIII. A su vez quiso dedicar un lugar para la devoci\u00f3n permanente de la Virgen, a quien se atribu\u00eda la ayuda decisiva para vencer en la \u00e9pica batalla. Eligi\u00f3 esta cueva que ya de antiguo y antes de la llegada de los romanos, hab\u00eda sido utilizada para diversos rituales celtas.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Posteriormente, los sucesores en el trono de D. Pelayo, el rey Alfonso I y su esposa D\u00f1a. Hermelinda, mandaron construir una iglesia y un monasterio benedictino.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">En la Cueva podemos encontrar a la derecha, poco antes de la imagen de la Virgen, el sepulcro de D. Pelayo. Y un poco m\u00e1s escondido se encuentra tambi\u00e9n el sepulcro de D. Alfonso I y su mujer Hermelinda (hija de D. Pelayo).<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">A unos pocos metros de la cueva de Santina se encuentra la Bas\u00edlica de Santa Mar\u00eda la real de Covadonga. Fue el Arzobispo de Oviedo D. Benito Sanz y Flor\u00e9s el impulsor de la construcci\u00f3n de un gran templo monumental que devolviera a Covadonga el esplendor de otros tiempos. Comenz\u00f3 su construcci\u00f3n en 1886 y fue bendecida e inaugurada el 7 de septiembre de 1901. Encarga para ello los planos a Roberto Frassinelli, aunque el proyecto definitivo lo culminar\u00eda su sucesor Federico Aparici.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Es de estilo Neo-Rom\u00e1nico, est\u00e1 hecha en piedra ros\u00e1cea y marm\u00f3rea sacada de las mismas monta\u00f1as de Covadonga y consta de una nave central y tres \u00e1bsides escalonados, crucero y dos altas torres en la fachada occidental en la que se abre un p\u00f3rtico de triple arco.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">En el interior destacan algunas obras de arte como un cuadro de Luis de Madrazo que representa la \u00abProclamaci\u00f3n de Rey Pelayo\u00bb, otro de Vicente Carducho que representa \u00abla Anunciaci\u00f3n\u00bb y una bell\u00edsima imagen de Nuestra Se\u00f1ora hecha por el escultor catal\u00e1n Juan Sams\u00f3.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Tambi\u00e9n el visitante podr\u00e1 apreciar detr\u00e1s del altar una r\u00e9plica de la Cruz de la Victoria, obra de Miranda, a la derecha la Capilla de San Pedro Poveda, a la izquierda la Capilla del Sant\u00edsimo y arriba en el lateral se puede ver el \u00f3rgano, inaugurado en el a\u00f1o 2001.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">La cripta de la Bas\u00edlica de Covadonga es un espacio de culto muy especial, y como tantos lugares en el Real Sitio guarda fascinantes historias.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Las obras de la cripta fueron dirigidas por Roberto Frassinelli, el famoso \u201calem\u00e1n de Corao\u201d. Las Asturias indianas tienen presente la influencia en Covadonga y una muestra de ello es el altar de m\u00e1rmol de la cripta, que fue donado por Antonio Monasterio, asturiano residente en Cuba. Sobre este altar luce una virgen de marfil, y que le da un aire distinto y cosmopolita a una cripta que tiene algunas obras notables de imaginer\u00eda, y cuya luz natural se cuela a trav\u00e9s de unas vidrieras, y que cuenta adem\u00e1s con un enorme confesionario.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Por ultimo no debemos olvidar hablar del Museo donde los visitantes podr\u00e1n ver y conocer la historia de este hist\u00f3rico Santuario desde la legendaria batalla con la que dio comienzo la Reconquista, iniciada por Don Pelayo (Fundador de la Monarqu\u00eda), as\u00ed como tambi\u00e9n las distintas transformaciones que ha sufrido a lo largo de su historia.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">La imagen de la Virgen de Covadonga nos recuerda y hace vivir lo que ella representa en la historia de la salvaci\u00f3n para Jes\u00fas y para sus disc\u00edpulos de ayer y de hoy. Esta cordialmente arraigada en el pueblo asturiano y espa\u00f1ol. Sobre todo, en los emigrantes que, alejados un tiempo de su tierrina natal, al retornar, sienten como un deber cordial acudir a Covadonga, como se acude al hogar de la Madre. Es un signo que, por encima de cualquier divisi\u00f3n, une a todos los hijos de este territorio que llamamos Asturias.<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>La&nbsp;Santa Cueva de Covadonga&nbsp;es un santuario cat\u00f3lico&nbsp;situado en el Principado de Asturias en el norte de Espa\u00f1a. Se trata de una gruta en las estribaciones del Monte Auseva, en los Picos de Europa. Aqu\u00ed se encuentra la Virgen de Covadonga, tambi\u00e9n llamada cari\u00f1osamente por los asturianos \u00abLa Santina\u00bb. El nombre de Covadonga significa Cueva de&hellip; <a class=\"more-link\" href=\"https:\/\/catholic-television.com\/es\/santuario-de-la-virgen-de-covadonga\/\">Seguir leyendo <span class=\"screen-reader-text\">Santuario de la Virgen de Covadonga<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":4072,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"footnotes":""},"categories":[668,663,929],"tags":[9874,9875,9870,9872,9867,9869,9866,9868,9871,9873,9876,9865,9864],"class_list":["post-4071","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-bienvenidos","category-compania-de-jesus","category-santos-lugares-sagrados","tag-basilica-santa-maria-covadonga","tag-batalla-de-covadonga","tag-capilla-san-pedro-poveda","tag-escultor-catalan-juan-samso","tag-la-santina","tag-nuestra-senora","tag-patrona-de-asturias","tag-principado-de-asturias","tag-rey-pelayo","tag-roberto-frassinelli","tag-santuario-asturias","tag-santuario-covadonga","tag-virgen-de-covadonga","post_format-post-format-video","entry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Santuario de la Virgen de Covadonga | Patrona de Asturias | La Santina<\/title>\n<meta name=\"description\" content=\"La\u00a0Santa Cueva de Covadonga\u00a0es un santuario cat\u00f3lico\u00a0situado en el Principado de Asturias en el norte de Espa\u00f1a. Se trata de una gruta en las estribaciones\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/catholic-television.com\/es\/santuario-de-la-virgen-de-covadonga\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Santuario de la Virgen de Covadonga | Patrona de Asturias | La Santina\" \/>\n<meta property=\"og:description\" content=\"La\u00a0Santa Cueva de Covadonga\u00a0es un santuario cat\u00f3lico\u00a0situado en el Principado de Asturias en el norte de Espa\u00f1a. Se trata de una gruta en las estribaciones\" \/>\n<meta property=\"og:url\" content=\"https:\/\/catholic-television.com\/es\/santuario-de-la-virgen-de-covadonga\/\" \/>\n<meta property=\"og:site_name\" content=\"Catholic-television\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/catholic.television.production\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-26T20:20:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-12-04T10:16:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/catholic-television.com\/wp-content\/uploads\/2019\/09\/Santuario-de-la-Virgen-de-Covadonga-Patrona-de-Asturias-La-Santina.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"David-Rothfuss\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@catholictele\" \/>\n<meta name=\"twitter:site\" content=\"@catholictele\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"David-Rothfuss\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/santuario-de-la-virgen-de-covadonga\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/santuario-de-la-virgen-de-covadonga\\\/\"},\"author\":{\"name\":\"David-Rothfuss\",\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/#\\\/schema\\\/person\\\/e012ff19693cfabdf8f197251428c7dd\"},\"headline\":\"Santuario de la Virgen de Covadonga\",\"datePublished\":\"2019-09-26T20:20:51+00:00\",\"dateModified\":\"2022-12-04T10:16:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/santuario-de-la-virgen-de-covadonga\\\/\"},\"wordCount\":1182,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/santuario-de-la-virgen-de-covadonga\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/catholic-television.com\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/Santuario-de-la-Virgen-de-Covadonga-Patrona-de-Asturias-La-Santina.jpg\",\"keywords\":[\"Bas\u00edlica Santa Mar\u00eda Covadonga\",\"batalla de Covadonga\",\"Capilla San Pedro Poveda\",\"escultor catal\u00e1n Juan Sams\u00f3\",\"La Santina\",\"Nuestra Se\u00f1ora\",\"Patrona de Asturias\",\"Principado de Asturias\",\"Rey Pelayo\",\"Roberto Frassinelli\",\"Santuario Asturias\",\"Santuario Covadonga\",\"Virgen de Covadonga\"],\"articleSection\":[\"Bienvenidos\",\"Compa\u00f1\u00eda de Jes\u00fas\",\"Santos y lugares sagrados\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/catholic-television.com\\\/es\\\/santuario-de-la-virgen-de-covadonga\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/santuario-de-la-virgen-de-covadonga\\\/\",\"url\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/santuario-de-la-virgen-de-covadonga\\\/\",\"name\":\"Santuario de la Virgen de Covadonga | Patrona de Asturias | La Santina\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/santuario-de-la-virgen-de-covadonga\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/santuario-de-la-virgen-de-covadonga\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/catholic-television.com\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/Santuario-de-la-Virgen-de-Covadonga-Patrona-de-Asturias-La-Santina.jpg\",\"datePublished\":\"2019-09-26T20:20:51+00:00\",\"dateModified\":\"2022-12-04T10:16:51+00:00\",\"description\":\"La\u00a0Santa Cueva de Covadonga\u00a0es un santuario cat\u00f3lico\u00a0situado en el Principado de Asturias en el norte de Espa\u00f1a. Se trata de una gruta en las estribaciones\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/santuario-de-la-virgen-de-covadonga\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/catholic-television.com\\\/es\\\/santuario-de-la-virgen-de-covadonga\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/santuario-de-la-virgen-de-covadonga\\\/#primaryimage\",\"url\":\"https:\\\/\\\/catholic-television.com\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/Santuario-de-la-Virgen-de-Covadonga-Patrona-de-Asturias-La-Santina.jpg\",\"contentUrl\":\"https:\\\/\\\/catholic-television.com\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/Santuario-de-la-Virgen-de-Covadonga-Patrona-de-Asturias-La-Santina.jpg\",\"width\":1024,\"height\":576,\"caption\":\"Santuario de la Virgen de Covadonga - Patrona de Asturias - La Santina\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/santuario-de-la-virgen-de-covadonga\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/?lang=es\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Santuario de la Virgen de Covadonga\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/\",\"name\":\"Catholic-television\",\"description\":\"Catholic Television\",\"publisher\":{\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/#organization\",\"name\":\"Catholic-television\",\"url\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/catholic-television.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/catholic-tv_ok2.png\",\"contentUrl\":\"https:\\\/\\\/catholic-television.com\\\/wp-content\\\/uploads\\\/2019\\\/06\\\/catholic-tv_ok2.png\",\"width\":303,\"height\":99,\"caption\":\"Catholic-television\"},\"image\":{\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/catholic.television.production\\\/\",\"https:\\\/\\\/x.com\\\/catholictele\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/catholic-television.com\\\/es\\\/#\\\/schema\\\/person\\\/e012ff19693cfabdf8f197251428c7dd\",\"name\":\"David-Rothfuss\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1bdadd82646ed1b1b380724d24278de576a4d7a2551be5b679e8aa17e11be7f6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1bdadd82646ed1b1b380724d24278de576a4d7a2551be5b679e8aa17e11be7f6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/1bdadd82646ed1b1b380724d24278de576a4d7a2551be5b679e8aa17e11be7f6?s=96&d=mm&r=g\",\"caption\":\"David-Rothfuss\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Santuario de la Virgen de Covadonga | Patrona de Asturias | La Santina","description":"La\u00a0Santa Cueva de Covadonga\u00a0es un santuario cat\u00f3lico\u00a0situado en el Principado de Asturias en el norte de Espa\u00f1a. Se trata de una gruta en las estribaciones","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/catholic-television.com\/es\/santuario-de-la-virgen-de-covadonga\/","og_locale":"es_ES","og_type":"article","og_title":"Santuario de la Virgen de Covadonga | Patrona de Asturias | La Santina","og_description":"La\u00a0Santa Cueva de Covadonga\u00a0es un santuario cat\u00f3lico\u00a0situado en el Principado de Asturias en el norte de Espa\u00f1a. Se trata de una gruta en las estribaciones","og_url":"https:\/\/catholic-television.com\/es\/santuario-de-la-virgen-de-covadonga\/","og_site_name":"Catholic-television","article_publisher":"https:\/\/www.facebook.com\/catholic.television.production\/","article_published_time":"2019-09-26T20:20:51+00:00","article_modified_time":"2022-12-04T10:16:51+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/catholic-television.com\/wp-content\/uploads\/2019\/09\/Santuario-de-la-Virgen-de-Covadonga-Patrona-de-Asturias-La-Santina.jpg","type":"image\/jpeg"}],"author":"David-Rothfuss","twitter_card":"summary_large_image","twitter_creator":"@catholictele","twitter_site":"@catholictele","twitter_misc":{"Escrito por":"David-Rothfuss","Tiempo de lectura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/catholic-television.com\/es\/santuario-de-la-virgen-de-covadonga\/#article","isPartOf":{"@id":"https:\/\/catholic-television.com\/es\/santuario-de-la-virgen-de-covadonga\/"},"author":{"name":"David-Rothfuss","@id":"https:\/\/catholic-television.com\/es\/#\/schema\/person\/e012ff19693cfabdf8f197251428c7dd"},"headline":"Santuario de la Virgen de Covadonga","datePublished":"2019-09-26T20:20:51+00:00","dateModified":"2022-12-04T10:16:51+00:00","mainEntityOfPage":{"@id":"https:\/\/catholic-television.com\/es\/santuario-de-la-virgen-de-covadonga\/"},"wordCount":1182,"commentCount":0,"publisher":{"@id":"https:\/\/catholic-television.com\/es\/#organization"},"image":{"@id":"https:\/\/catholic-television.com\/es\/santuario-de-la-virgen-de-covadonga\/#primaryimage"},"thumbnailUrl":"https:\/\/catholic-television.com\/wp-content\/uploads\/2019\/09\/Santuario-de-la-Virgen-de-Covadonga-Patrona-de-Asturias-La-Santina.jpg","keywords":["Bas\u00edlica Santa Mar\u00eda Covadonga","batalla de Covadonga","Capilla San Pedro Poveda","escultor catal\u00e1n Juan Sams\u00f3","La Santina","Nuestra Se\u00f1ora","Patrona de Asturias","Principado de Asturias","Rey Pelayo","Roberto Frassinelli","Santuario Asturias","Santuario Covadonga","Virgen de Covadonga"],"articleSection":["Bienvenidos","Compa\u00f1\u00eda de Jes\u00fas","Santos y lugares sagrados"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/catholic-television.com\/es\/santuario-de-la-virgen-de-covadonga\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/catholic-television.com\/es\/santuario-de-la-virgen-de-covadonga\/","url":"https:\/\/catholic-television.com\/es\/santuario-de-la-virgen-de-covadonga\/","name":"Santuario de la Virgen de Covadonga | Patrona de Asturias | La Santina","isPartOf":{"@id":"https:\/\/catholic-television.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/catholic-television.com\/es\/santuario-de-la-virgen-de-covadonga\/#primaryimage"},"image":{"@id":"https:\/\/catholic-television.com\/es\/santuario-de-la-virgen-de-covadonga\/#primaryimage"},"thumbnailUrl":"https:\/\/catholic-television.com\/wp-content\/uploads\/2019\/09\/Santuario-de-la-Virgen-de-Covadonga-Patrona-de-Asturias-La-Santina.jpg","datePublished":"2019-09-26T20:20:51+00:00","dateModified":"2022-12-04T10:16:51+00:00","description":"La\u00a0Santa Cueva de Covadonga\u00a0es un santuario cat\u00f3lico\u00a0situado en el Principado de Asturias en el norte de Espa\u00f1a. Se trata de una gruta en las estribaciones","breadcrumb":{"@id":"https:\/\/catholic-television.com\/es\/santuario-de-la-virgen-de-covadonga\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/catholic-television.com\/es\/santuario-de-la-virgen-de-covadonga\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/catholic-television.com\/es\/santuario-de-la-virgen-de-covadonga\/#primaryimage","url":"https:\/\/catholic-television.com\/wp-content\/uploads\/2019\/09\/Santuario-de-la-Virgen-de-Covadonga-Patrona-de-Asturias-La-Santina.jpg","contentUrl":"https:\/\/catholic-television.com\/wp-content\/uploads\/2019\/09\/Santuario-de-la-Virgen-de-Covadonga-Patrona-de-Asturias-La-Santina.jpg","width":1024,"height":576,"caption":"Santuario de la Virgen de Covadonga - Patrona de Asturias - La Santina"},{"@type":"BreadcrumbList","@id":"https:\/\/catholic-television.com\/es\/santuario-de-la-virgen-de-covadonga\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/catholic-television.com\/es\/?lang=es"},{"@type":"ListItem","position":2,"name":"Santuario de la Virgen de Covadonga"}]},{"@type":"WebSite","@id":"https:\/\/catholic-television.com\/es\/#website","url":"https:\/\/catholic-television.com\/es\/","name":"Catholic-television","description":"Catholic Television","publisher":{"@id":"https:\/\/catholic-television.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/catholic-television.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/catholic-television.com\/es\/#organization","name":"Catholic-television","url":"https:\/\/catholic-television.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/catholic-television.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/catholic-television.com\/wp-content\/uploads\/2019\/06\/catholic-tv_ok2.png","contentUrl":"https:\/\/catholic-television.com\/wp-content\/uploads\/2019\/06\/catholic-tv_ok2.png","width":303,"height":99,"caption":"Catholic-television"},"image":{"@id":"https:\/\/catholic-television.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/catholic.television.production\/","https:\/\/x.com\/catholictele"]},{"@type":"Person","@id":"https:\/\/catholic-television.com\/es\/#\/schema\/person\/e012ff19693cfabdf8f197251428c7dd","name":"David-Rothfuss","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/1bdadd82646ed1b1b380724d24278de576a4d7a2551be5b679e8aa17e11be7f6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/1bdadd82646ed1b1b380724d24278de576a4d7a2551be5b679e8aa17e11be7f6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/1bdadd82646ed1b1b380724d24278de576a4d7a2551be5b679e8aa17e11be7f6?s=96&d=mm&r=g","caption":"David-Rothfuss"}}]}},"_links":{"self":[{"href":"https:\/\/catholic-television.com\/es\/wp-json\/wp\/v2\/posts\/4071","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/catholic-television.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/catholic-television.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/catholic-television.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/catholic-television.com\/es\/wp-json\/wp\/v2\/comments?post=4071"}],"version-history":[{"count":2,"href":"https:\/\/catholic-television.com\/es\/wp-json\/wp\/v2\/posts\/4071\/revisions"}],"predecessor-version":[{"id":17312,"href":"https:\/\/catholic-television.com\/es\/wp-json\/wp\/v2\/posts\/4071\/revisions\/17312"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/catholic-television.com\/es\/wp-json\/wp\/v2\/media\/4072"}],"wp:attachment":[{"href":"https:\/\/catholic-television.com\/es\/wp-json\/wp\/v2\/media?parent=4071"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/catholic-television.com\/es\/wp-json\/wp\/v2\/categories?post=4071"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/catholic-television.com\/es\/wp-json\/wp\/v2\/tags?post=4071"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}